{"id":2526,"date":"2018-07-09T13:54:50","date_gmt":"2018-07-09T13:54:50","guid":{"rendered":"http:\/\/arsitalica.it\/?p=2526\/"},"modified":"2018-07-23T13:38:02","modified_gmt":"2018-07-23T13:38:02","slug":"ilfalconiere-cortona-salottidelgusto-strade-stellate","status":"publish","type":"post","link":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/","title":{"rendered":"Il Falconiere (Relais &#038; Chateau) &#8211; Salotti del Gusto"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2547,2565,2548,2549,2550,2551,2552,2553,2554,2555,2556,2557,2558,2559,2560,2561,2562,2563,2566&#8243; layout=&#8221;3&#8243; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2547,2565,2548,2549,2550,2551,2552,2553,2554,2555,2556,2557,2558,2559,2560,2561,2562,2563,2566&#8243; layout=&#8221;3&#8243; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":3,"featured_media":2547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[215,216,176,212],"class_list":{"0":"post-2526","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eventi-en","8":"tag-relais-chateau-en","9":"tag-relais-il-falconiere-en","10":"tag-salotti-del-gusto-en","11":"tag-strade-stellate-en"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Falconiere (Relais &amp; Chateau) - Salotti del Gusto &#8211; Ars Italica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Falconiere (Relais &amp; Chateau) - Salotti del Gusto &#8211; Ars Italica\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2547,2565,2548,2549,2550,2551,2552,2553,2554,2555,2556,2557,2558,2559,2560,2561,2562,2563,2566&#8243; layout=&#8221;3&#8243; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221;][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\" \/>\n<meta property=\"og:site_name\" content=\"Ars Italica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArsItalicaCaviar\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-09T13:54:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-23T13:38:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paolo Pojano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paolo Pojano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\"},\"author\":{\"name\":\"Paolo Pojano\",\"@id\":\"https:\/\/arsitalica.it\/en\/#\/schema\/person\/4a7186c907cc5c3726cfdbde90e4a7d0\"},\"headline\":\"Il Falconiere (Relais &#038; Chateau) &#8211; Salotti del Gusto\",\"datePublished\":\"2018-07-09T13:54:50+00:00\",\"dateModified\":\"2018-07-23T13:38:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\"},\"wordCount\":90,\"publisher\":{\"@id\":\"https:\/\/arsitalica.it\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg\",\"keywords\":[\"relais &amp; chateau\",\"relais il falconiere\",\"salotti del gusto\",\"strade stellate\"],\"articleSection\":[\"Eventi EN\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\",\"url\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\",\"name\":\"Il Falconiere (Relais & Chateau) - Salotti del Gusto &#8211; Ars Italica\",\"isPartOf\":{\"@id\":\"https:\/\/arsitalica.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg\",\"datePublished\":\"2018-07-09T13:54:50+00:00\",\"dateModified\":\"2018-07-23T13:38:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage\",\"url\":\"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg\",\"contentUrl\":\"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg\",\"width\":1900,\"height\":1425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arsitalica.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Falconiere (Relais &#038; Chateau) &#8211; Salotti del Gusto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arsitalica.it\/en\/#website\",\"url\":\"https:\/\/arsitalica.it\/en\/\",\"name\":\"Ars Italica\",\"description\":\"La nobilt\u00e0 del gusto\",\"publisher\":{\"@id\":\"https:\/\/arsitalica.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arsitalica.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arsitalica.it\/en\/#organization\",\"name\":\"Italian Caviar\",\"url\":\"https:\/\/arsitalica.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/arsitalica.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arsitalica.it\/wp-content\/uploads\/2017\/10\/logo-ars-italica-landing-225x218-oro.png\",\"contentUrl\":\"https:\/\/arsitalica.it\/wp-content\/uploads\/2017\/10\/logo-ars-italica-landing-225x218-oro.png\",\"width\":225,\"height\":218,\"caption\":\"Italian Caviar\"},\"image\":{\"@id\":\"https:\/\/arsitalica.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ArsItalicaCaviar\/\",\"https:\/\/www.instagram.com\/arsitalicacaviar\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/arsitalica.it\/en\/#\/schema\/person\/4a7186c907cc5c3726cfdbde90e4a7d0\",\"name\":\"Paolo Pojano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/arsitalica.it\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2ce05f8e09c8f5a20c7e0f7d1c2f682a6b525044a462204eb0a3f47e3a66de23?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2ce05f8e09c8f5a20c7e0f7d1c2f682a6b525044a462204eb0a3f47e3a66de23?s=96&d=identicon&r=g\",\"caption\":\"Paolo Pojano\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Falconiere (Relais & Chateau) - Salotti del Gusto &#8211; Ars Italica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/","og_locale":"en_US","og_type":"article","og_title":"Il Falconiere (Relais & Chateau) - Salotti del Gusto &#8211; Ars Italica","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2547,2565,2548,2549,2550,2551,2552,2553,2554,2555,2556,2557,2558,2559,2560,2561,2562,2563,2566&#8243; layout=&#8221;3&#8243; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221;][\/vc_column][\/vc_row]","og_url":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/","og_site_name":"Ars Italica","article_publisher":"https:\/\/www.facebook.com\/ArsItalicaCaviar\/","article_published_time":"2018-07-09T13:54:50+00:00","article_modified_time":"2018-07-23T13:38:02+00:00","og_image":[{"width":1900,"height":1425,"url":"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg","type":"image\/jpeg"}],"author":"Paolo Pojano","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Paolo Pojano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#article","isPartOf":{"@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/"},"author":{"name":"Paolo Pojano","@id":"https:\/\/arsitalica.it\/en\/#\/schema\/person\/4a7186c907cc5c3726cfdbde90e4a7d0"},"headline":"Il Falconiere (Relais &#038; Chateau) &#8211; Salotti del Gusto","datePublished":"2018-07-09T13:54:50+00:00","dateModified":"2018-07-23T13:38:02+00:00","mainEntityOfPage":{"@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/"},"wordCount":90,"publisher":{"@id":"https:\/\/arsitalica.it\/en\/#organization"},"image":{"@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage"},"thumbnailUrl":"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg","keywords":["relais &amp; chateau","relais il falconiere","salotti del gusto","strade stellate"],"articleSection":["Eventi EN"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/","url":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/","name":"Il Falconiere (Relais & Chateau) - Salotti del Gusto &#8211; Ars Italica","isPartOf":{"@id":"https:\/\/arsitalica.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage"},"image":{"@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage"},"thumbnailUrl":"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg","datePublished":"2018-07-09T13:54:50+00:00","dateModified":"2018-07-23T13:38:02+00:00","breadcrumb":{"@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#primaryimage","url":"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg","contentUrl":"https:\/\/arsitalica.it\/wp-content\/uploads\/2018\/07\/IMG_7863.jpg","width":1900,"height":1425},{"@type":"BreadcrumbList","@id":"https:\/\/arsitalica.it\/en\/eventi-en\/ilfalconiere-cortona-salottidelgusto-strade-stellate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arsitalica.it\/en\/"},{"@type":"ListItem","position":2,"name":"Il Falconiere (Relais &#038; Chateau) &#8211; Salotti del Gusto"}]},{"@type":"WebSite","@id":"https:\/\/arsitalica.it\/en\/#website","url":"https:\/\/arsitalica.it\/en\/","name":"Ars Italica","description":"La nobilt\u00e0 del gusto","publisher":{"@id":"https:\/\/arsitalica.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arsitalica.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/arsitalica.it\/en\/#organization","name":"Italian Caviar","url":"https:\/\/arsitalica.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arsitalica.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/arsitalica.it\/wp-content\/uploads\/2017\/10\/logo-ars-italica-landing-225x218-oro.png","contentUrl":"https:\/\/arsitalica.it\/wp-content\/uploads\/2017\/10\/logo-ars-italica-landing-225x218-oro.png","width":225,"height":218,"caption":"Italian Caviar"},"image":{"@id":"https:\/\/arsitalica.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArsItalicaCaviar\/","https:\/\/www.instagram.com\/arsitalicacaviar\/"]},{"@type":"Person","@id":"https:\/\/arsitalica.it\/en\/#\/schema\/person\/4a7186c907cc5c3726cfdbde90e4a7d0","name":"Paolo Pojano","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arsitalica.it\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2ce05f8e09c8f5a20c7e0f7d1c2f682a6b525044a462204eb0a3f47e3a66de23?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ce05f8e09c8f5a20c7e0f7d1c2f682a6b525044a462204eb0a3f47e3a66de23?s=96&d=identicon&r=g","caption":"Paolo Pojano"}}]}},"_links":{"self":[{"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/posts\/2526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/comments?post=2526"}],"version-history":[{"count":2,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/posts\/2526\/revisions"}],"predecessor-version":[{"id":2575,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/posts\/2526\/revisions\/2575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/media\/2547"}],"wp:attachment":[{"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/media?parent=2526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/categories?post=2526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arsitalica.it\/en\/wp-json\/wp\/v2\/tags?post=2526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}